{"id":76,"count":1,"description":"","link":"https:\/\/hofstadtax.nl\/en\/tag\/inspectie-en\/","name":"inspectie","slug":"inspectie-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>inspectie Archieven - De Hofstad Taxicentrale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hofstadtax.nl\/en\/tag\/inspectie-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"inspectie Archieven - De Hofstad Taxicentrale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hofstadtax.nl\/en\/tag\/inspectie-en\/\" \/>\n<meta property=\"og:site_name\" content=\"De Hofstad Taxicentrale\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"inspectie Archieven - De Hofstad Taxicentrale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hofstadtax.nl\/en\/tag\/inspectie-en\/","og_locale":"en_US","og_type":"article","og_title":"inspectie Archieven - De Hofstad Taxicentrale","og_url":"https:\/\/hofstadtax.nl\/en\/tag\/inspectie-en\/","og_site_name":"De Hofstad Taxicentrale","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hofstadtax.nl\/en\/tag\/inspectie-en\/","url":"https:\/\/hofstadtax.nl\/en\/tag\/inspectie-en\/","name":"inspectie Archieven - De Hofstad Taxicentrale","isPartOf":{"@id":"https:\/\/hofstadtax.nl\/#website"},"breadcrumb":{"@id":"https:\/\/hofstadtax.nl\/en\/tag\/inspectie-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/hofstadtax.nl\/en\/tag\/inspectie-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hofstadtax.nl\/en\/"},{"@type":"ListItem","position":2,"name":"inspectie"}]},{"@type":"WebSite","@id":"https:\/\/hofstadtax.nl\/#website","url":"https:\/\/hofstadtax.nl\/","name":"De Hofstad Taxicentrale","description":"De beste taxi voor Den Haag e.o.","publisher":{"@id":"https:\/\/hofstadtax.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hofstadtax.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/hofstadtax.nl\/#organization","name":"Hofstadtax","url":"https:\/\/hofstadtax.nl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hofstadtax.nl\/#\/schema\/logo\/image\/","url":"https:\/\/hofstadtax.nl\/wp-content\/uploads\/2017\/12\/1200x630bb-1.jpg","contentUrl":"https:\/\/hofstadtax.nl\/wp-content\/uploads\/2017\/12\/1200x630bb-1.jpg","width":630,"height":630,"caption":"Hofstadtax"},"image":{"@id":"https:\/\/hofstadtax.nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hofstadtax.nl\/en\/wp-json\/wp\/v2\/tags\/76","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hofstadtax.nl\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/hofstadtax.nl\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/hofstadtax.nl\/en\/wp-json\/wp\/v2\/posts?tags=76"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}